{"id":19056,"date":"2020-05-16T17:30:56","date_gmt":"2020-05-16T15:30:56","guid":{"rendered":"https:\/\/www.prachelle.com\/non%20class\u00e9\/versailles-golden-marble-leggings-with-stripes\/"},"modified":"2020-05-23T09:55:06","modified_gmt":"2020-05-23T07:55:06","slug":"versailles-legging-marbre-dore-avec-bandes","status":"publish","type":"product","link":"https:\/\/www.prachelle.com\/fr\/leggings-france\/versailles-legging-marbre-dore-avec-bandes\/","title":{"rendered":"Versailles | Legging Marbre Dor\u00e9 avec Bandes"},"content":{"rendered":"<p>Combinez l&rsquo;artistique de l&rsquo;or avec le minimalisme du blanc avec ce legging \u00e0 taille haute fabriqu\u00e9 \u00e0 la main. Ce legging blanc est d\u00e9cor\u00e9 de marbrures dor\u00e9es qui parcourt l&rsquo;ensemble du legging, avec trois bandes dor\u00e9es sur chaque jambe. Vous serez surprise du confort incroyable et de la solidit\u00e9 de son \u00e9lasticit\u00e9 d\u00e8s que vous le mettrez, avec un tissu extra-doux pour des s\u00e9ances de sport amplifi\u00e9es. Fait main avec un fil de microfibre doux, durable et confortable, le tissu dispose d&rsquo;une technologie de s\u00e9chage rapide de la transpiration. D\u00e9cor\u00e9e du logo Prachelle dor\u00e9, la ceinture montante est \u00e9lastique sans comprimer le ventre. Tout a \u00e9t\u00e9 pens\u00e9 pour vous garantir un legging magnifique et technique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Combinez l&rsquo;artistique de l&rsquo;or avec le minimalisme du blanc avec ce legging \u00e0 taille haute fabriqu\u00e9 \u00e0 la main.<\/p>\n","protected":false},"featured_media":19036,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[622],"product_tag":[644],"class_list":{"0":"post-19056","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-leggings-france","7":"product_tag-prachelle-fr","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product\/19056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/comments?post=19056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media\/19036"}],"wp:attachment":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media?parent=19056"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_brand?post=19056"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_cat?post=19056"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_tag?post=19056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}