{"id":18737,"date":"2020-05-27T11:48:20","date_gmt":"2020-05-30T15:13:34","guid":{"rendered":"https:\/\/www.prachelle.com\/non%20class\u00e9\/caeruleum-blue-technical-capri-leggings\/"},"modified":"2020-05-30T17:13:34","modified_gmt":"2020-05-30T15:13:34","slug":"capri-technique-bleu-de-caeruleum-uni","status":"publish","type":"product","link":"https:\/\/www.prachelle.com\/fr\/capris-france\/capri-technique-bleu-de-caeruleum-uni\/","title":{"rendered":"Capri Technique Bleu de C\u00e6ruleum Uni"},"content":{"rendered":"<p>Capri technique bleu de c\u00e6ruleum uni. Un capri \u00e0 taille haute fait \u00e0 la main d\u00e9di\u00e9 \u00e0 la performance, au confort et \u00e0 la durabilit\u00e9. Entrejambe \u00e0 gousset triangulaire pour une incroyable solidit\u00e9 \u00e9lastique, couleur bleue de c\u00e6ruleum \u00e9clatante, tissu ultra doux au confort incroyable, ceinture montant qui ne compresse pas le ventre, tissu \u00e0 s\u00e9chage rapide, d\u00e9cor\u00e9 avec le logo Prachelle en blanc, squat proof, fait main avec un fil de microfibre doux et durable, coutures plates avec point de recouvrement pour supprimer les frottements, \u00e9tirement \u00e0 quatre voies pour une \u00e9lasticit\u00e9 des couleurs pr\u00e9serv\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capri technique bleu de c\u00e6ruleum uni. Un capri \u00e0 taille haute fait \u00e0 la main d\u00e9di\u00e9 \u00e0 la performance, au confort et \u00e0 la durabilit\u00e9.<\/p>\n","protected":false},"featured_media":18646,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[612],"product_tag":[644],"class_list":{"0":"post-18737","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-capris-france","7":"product_tag-prachelle-fr","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product\/18737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/comments?post=18737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media\/18646"}],"wp:attachment":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media?parent=18737"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_brand?post=18737"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18737"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}