{"id":18123,"date":"2020-05-13T09:32:56","date_gmt":"2020-05-13T07:32:56","guid":{"rendered":"https:\/\/www.prachelle.com\/non%20class\u00e9\/white-technical-leggings-with-black-stripes\/"},"modified":"2020-05-10T01:29:00","modified_gmt":"2020-05-09T23:29:00","slug":"legging-blanc-avec-bandes-noires","status":"publish","type":"product","link":"https:\/\/www.prachelle.com\/fr\/leggings-france\/legging-blanc-avec-bandes-noires\/","title":{"rendered":"Legging Blanc avec Bandes Noires"},"content":{"rendered":"<p>Legging technique blanc uni avec bandes noires. Portez un legging blanc \u00e0 taille haute fait \u00e0 la main con\u00e7u pour les performances, le confort et la durabilit\u00e9. Tissu \u00e0 s\u00e9chage rapide anti-transpiration, ceinture montante qui ne compresse pas le ventre, entrejambe \u00e0 gousset triangulaire pour une incroyable solidit\u00e9 \u00e9lastique, couleur blanche \u00e9clatante avec bandes noires au niveau des jambes, d\u00e9cor\u00e9 avec le logo Prachelle en d\u00e9grad\u00e9 rose et bleu, fait main avec un fil de microfibre doux et durable, coutures plates avec point de recouvrement pour supprimer les frottements, \u00e9tirement \u00e0 quatre voies pour une \u00e9lasticit\u00e9 des couleurs pr\u00e9serv\u00e9es, tissu ultra doux au confort incroyable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Legging technique blanc uni avec bandes noires. Portez un legging blanc \u00e0 taille haute fait \u00e0 la main con\u00e7u pour les performances, le confort et la durabilit\u00e9.<\/p>\n","protected":false},"featured_media":18097,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[622],"product_tag":[644],"class_list":{"0":"post-18123","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-leggings-france","7":"product_tag-prachelle-fr","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product\/18123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/comments?post=18123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media\/18097"}],"wp:attachment":[{"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/media?parent=18123"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_brand?post=18123"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_cat?post=18123"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.prachelle.com\/fr\/wp-json\/wp\/v2\/product_tag?post=18123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}